{"id":1120,"count":1,"description":"","link":"https:\/\/banulbotosanean.ro\/index.php\/tag\/105-controale-si-72-500-lei-in-amenzi-bilantul-itm-botosani-pe-octombrie\/","name":"105 controale \u0219i 72.500 lei \u00een amenzi: bilan\u021bul ITM Boto\u0219ani pe octombrie","slug":"105-controale-si-72-500-lei-in-amenzi-bilantul-itm-botosani-pe-octombrie","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/banulbotosanean.ro\/index.php\/wp-json\/wp\/v2\/tags\/1120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/banulbotosanean.ro\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/banulbotosanean.ro\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/banulbotosanean.ro\/index.php\/wp-json\/wp\/v2\/posts?tags=1120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}